{"id":21213,"date":"2026-05-12T19:01:43","date_gmt":"2026-05-12T18:01:43","guid":{"rendered":"https:\/\/informacionlocal.es\/tras-el-exito-de-su-primera-edicion-regresan-los-encuentros-de-mujeres-de-antigua\/"},"modified":"2026-05-12T19:01:43","modified_gmt":"2026-05-12T18:01:43","slug":"tras-el-exito-de-su-primera-edicion-regresan-los-encuentros-de-mujeres-de-antigua","status":"publish","type":"post","link":"https:\/\/informacionlocal.es\/it\/tras-el-exito-de-su-primera-edicion-regresan-los-encuentros-de-mujeres-de-antigua\/","title":{"rendered":"Tras el \u00e9xito de su primera edici\u00f3n regresan los Encuentros de Mujeres de Antigua"},"content":{"rendered":"<div class=\"elementor-widget-container\">\n<p><strong>Tras el \u00e9xito de su primera edici\u00f3n regresan los Encuentros de Mujeres de Antigua<\/strong><\/p>\n<p><strong>\u2022 Inscripci\u00f3n gratuita llamando al 928549651. <\/strong><br \/><strong>\u2022 Imparte la reconocida y experimentada coach, Rosa Guerrero. <\/strong><br \/><strong>\u2022 Cuatro talleres los viernes 15 y 29 de mayo y 12 y 26 de junio de 17:00 a 20:00 horas en el Centro Posici\u00f3n Cero en Antigua. <\/strong><br \/><strong>\u2022 Los talleres finalizan con una celebraci\u00f3n y convivencia el 29 de julio en el SPA del centro de Thalasoterapia del Barcel\u00f3 en Caleta de Fuste.<\/strong><\/p>\n<p>El Ayuntamiento de Antigua organiza desde la concejal\u00eda de Servicios Sociales los Encuentros de Mujeres de Antigua, EMA2, tras el \u00e9xito de su primera edici\u00f3n, anuncia el alcalde, Mat\u00edas Pe\u00f1a, se trata de seguir impulsando talleres formativos y de ayuda personal, siempre de inscripci\u00f3n gratuita para facilitar la inscripci\u00f3n de toda persona que lo precise.<\/p>\n<p>Se trata de un programa gratuito de talleres de crecimiento personal dise\u00f1ado en esta ocasi\u00f3n, espec\u00edficamente para mujeres, afirma la concejala de \u00e1rea, Am\u00e9rica Soto Betancor, y que se desarrollar\u00e1 entre los meses de mayo y julio en el Centro Posici\u00f3n Cero en Antigua, dirigidos e impartidos por la reconocida coach Rosa Guerrero Merch\u00e1n.<\/p>\n<p>El ciclo propone un itinerario de cuatro encuentros tem\u00e1ticos y una jornada final de convivencia, orientados a proporcionar herramientas de autocuidado, sanaci\u00f3n y fortalecimiento emocional. Este programa reafirma el compromiso de Antigua con la igualdad y el bienestar de las mujeres, a\u00f1ade la concejala, ofreciendo un entorno seguro para el aprendizaje compartido.<\/p>\n<p>Los talleres cuentan con la colaboraci\u00f3n del Cabildo de Fuerteventura y se enmarcan en el Pacto de Estado contra la violencia de g\u00e9nero, se imparten los viernes de 17:00 a 20:00 horas, el 15 de mayo, dedicado a la Mujer y Desarrollo Personal con Estrategias de autocuidado y manejo del estr\u00e9s. El 29 de mayo, Mujer y Familia a trav\u00e9s de las Constelaciones Familiares. El 12 de junio, Mujer y Pareja, tratando la co-dependencia emocional. El 26 de junio, Mujer y Traumas, sobre el reconocimiento y reparaci\u00f3n de heridas del pasado.<\/p>\n<p>Como broche final a este ciclo, el 29 de julio se celebrar\u00e1 un Encuentro de Celebraci\u00f3n, Convivencia y Descanso en el SPA del Centro Thalassoterapia del Barcel\u00f3 en El Castillo, ofreciendo un espacio de relajaci\u00f3n y uni\u00f3n para todas las participantes.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>Tras el \u00e9xito de su primera edici\u00f3n regresan los Encuentros de Mujeres de Antigua<\/strong><\/p>\n","protected":false},"author":1,"featured_media":21215,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[59],"tags":[82],"class_list":["post-21213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antigua","tag-fuerteventura"],"jetpack_featured_media_url":"https:\/\/informacionlocal.es\/wp-content\/uploads\/2026\/05\/ema3.jpeg","_links":{"self":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/21213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/comments?post=21213"}],"version-history":[{"count":0,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/21213\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media\/21215"}],"wp:attachment":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media?parent=21213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/categories?post=21213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/tags?post=21213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}