{"id":21119,"date":"2026-05-11T12:02:11","date_gmt":"2026-05-11T11:02:11","guid":{"rendered":"https:\/\/informacionlocal.es\/la-inteligencia-artificial-abre-una-nueva-puerta-al-patrimonio-arqueologico-canario\/"},"modified":"2026-05-11T12:02:11","modified_gmt":"2026-05-11T11:02:11","slug":"la-inteligencia-artificial-abre-una-nueva-puerta-al-patrimonio-arqueologico-canario","status":"publish","type":"post","link":"https:\/\/informacionlocal.es\/it\/la-inteligencia-artificial-abre-una-nueva-puerta-al-patrimonio-arqueologico-canario\/","title":{"rendered":"\ufeffLa inteligencia artificial abre una nueva puerta al patrimonio arqueol\u00f3gico canario"},"content":{"rendered":"<div class=\"entry-content\"><strong>11 mayo, 2026<\/strong><\/p>\n<p><em><strong>El Museo Arqueol\u00f3gico de Fuerteventura acoger\u00e1 el 20 de mayo la validaci\u00f3n de D.A.R.Y.L., una herramienta innovadora desarrollada dentro del proyecto LegacIA para acercar la cultura a la ciudadan\u00eda<\/strong><\/em><\/p>\n<p>El consejero de Cultura, Patrimonio Cultural e Innovaci\u00f3n del Cabildo de Fuerteventura, Rayco Le\u00f3n Jord\u00e1n, el director de la Agencia Canaria de Investigaci\u00f3n, Innovaci\u00f3n y Sociedad de la Informaci\u00f3n (ACIISI), Javier Franco Hormiga; y el director de El Museo Canario, Daniel P\u00e9rez Est\u00e9vez, presentaron este viernes la jornada de experimentaci\u00f3n y validaci\u00f3n del proyecto LegacIA, que se celebrar\u00e1 el pr\u00f3ximo 20 de mayo en el Museo Arqueol\u00f3gico de Fuerteventura (MAF).<\/p>\n<p>La iniciativa convertir\u00e1 al MAF en un espacio de pruebas en entorno real para D.A.R.Y.L., un asistente de inteligencia artificial accesible desde dispositivos m\u00f3viles y dise\u00f1ado para mejorar la interacci\u00f3n de la ciudadan\u00eda con los espacios muse\u00edsticos y el patrimonio arqueol\u00f3gico.<\/p>\n<p>La jornada permitir\u00e1 testar directamente la herramienta con usuarios y usuarias en un entorno cultural abierto, evaluando aspectos relacionados con la accesibilidad, la utilidad de la experiencia y la capacidad de la inteligencia artificial para facilitar nuevas formas de acceso al conocimiento patrimonial.<\/p>\n<p>Durante la presentaci\u00f3n, el de Cultura, Patrimonio Cultural e Innovaci\u00f3n del Cabildo de Fuerteventura, Rayco Le\u00f3n Jord\u00e1n, destac\u00f3 que \u201cmejorar la experiencia del visitante es fundamental en los museos y aqu\u00ed juega un papel clave la tecnolog\u00eda para asistir al visitante, ampliando las formas en el que la experiencia se desarrolla\u201d.<\/p>\n<p>Por su parte, el director de El Museo Canario, Daniel P\u00e9rez Est\u00e9vez, se\u00f1al\u00f3 que \u201cel proyecto LegacIA es una iniciativa para la creaci\u00f3n de oportunidades profesionales en la juventud canaria en el campo de la mediaci\u00f3n cultural. Se hace posible gracias a la Convocatoria de subvenciones de Innovaci\u00f3n Social de la ACIISI, que resulta fundamental para impulsar iniciativas que contribuyan a la inclusi\u00f3n, la cohesi\u00f3n y el empleo a trav\u00e9s de la innovaci\u00f3n. Gracias a esta aplicaci\u00f3n, las personas que visitan el MAF podr\u00e1n conocer su contenido con un agente virtual que propone rutas y expone contenidos de manera interactiva\u201d.<\/p>\n<p>La implantaci\u00f3n de este asistente de Inteligencia Artificial, que estar\u00e1 disponible en el MAF a partir del 18 de mayo con motivo del D\u00eda Internacional de los Museos, supone asimismo un recurso puntero para compartir el rico legado patrimonial del pueblo Majo con la sociedad y fomentar el turismo cultural. \u201cPara El Museo Canario es muy gratificante profundizar en la colaboraci\u00f3n mutua con el MAF, que ya se ha venido consolidando durante estos \u00faltimos a\u00f1os\u201d, apunt\u00f3 P\u00e9rez.<\/p>\n<p>El director de la ACIISI, Javier Franco Hormiga, explic\u00f3 que LegacIA representa \u201cmuy bien el modelo de innovaci\u00f3n que queremos impulsar desde Canarias: una innovaci\u00f3n \u00fatil, cercana, conectada con el territorio y con impacto directo en la ciudadan\u00eda\u201d. Franco record\u00f3 que desde 2023 la ACIISI ha consolidado una l\u00ednea estable de apoyo a la innovaci\u00f3n social mediante convocatorias p\u00fablicas financiadas con fondos europeos orientadas a conectar tecnolog\u00eda, conocimiento y transformaci\u00f3n social.<\/p>\n<p>En este periodo, la Agencia ha impulsado cuatro convocatorias consecutivas que han permitido respaldar 19 proyectos innovadores en Canarias, movilizando m\u00e1s de 2,1 millones de euros de inversi\u00f3n p\u00fablica. La financiaci\u00f3n destinada a esta l\u00ednea ha experimentado adem\u00e1s un crecimiento progresivo, pasando de m\u00e1s de 338.000 euros en 2023 a cerca de 900.000 euros en la convocatoria de 2026.<\/p>\n<p>\u201cEl valor diferencial de esta convocatoria es su conexi\u00f3n directa con la ciudadan\u00eda, porque no hablamos \u00fanicamente de desarrollo tecnol\u00f3gico, sino de proyectos capaces de mejorar la vida de las personas desde \u00e1mbitos como la accesibilidad, la cultura, la inclusi\u00f3n social o la digitalizaci\u00f3n\u201d, afirm\u00f3.<\/p>\n<p>El director de la ACIISI subray\u00f3 adem\u00e1s que LegacIA \u201ccombina patrimonio cultural, accesibilidad e inteligencia artificial para generar nuevas formas de interacci\u00f3n con los espacios muse\u00edsticos y acercar el conocimiento a la ciudadan\u00eda desde herramientas digitales innovadoras\u201d.<\/p>\n<p>La jornada del 20 de mayo se enmarca dentro de las acciones de validaci\u00f3n del proyecto y permitir\u00e1 analizar el comportamiento de D.A.R.Y.L. en un contexto real de uso, reforzando la apuesta de las instituciones participantes por una innovaci\u00f3n p\u00fablica orientada al impacto social y al acceso inclusivo a la cultura.<\/p>\n<p>\u201cQueremos seguir impulsando una innovaci\u00f3n que conecte tecnolog\u00eda y personas, una innovaci\u00f3n con impacto social y que ponga el conocimiento al servicio de la ciudadan\u00eda\u201d, concluy\u00f3 Javier Franco Hormiga.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>11 mayo, 2026 El Museo Arqueol\u00f3gico de Fuerteventura acoger\u00e1 el 20 de mayo la validaci\u00f3n de D.A.R.Y.L., una herramienta innovadora desarrollada dentro del proyecto LegacIA para acercar la cultura a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[58],"tags":[68,82,180],"class_list":["post-21119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cabildo","tag-convocatorias","tag-fuerteventura","tag-innovacion"],"jetpack_featured_media_url":"https:\/\/informacionlocal.es\/wp-content\/uploads\/2026\/05\/dg-1.jpeg","_links":{"self":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/21119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/comments?post=21119"}],"version-history":[{"count":0,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/21119\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media\/21121"}],"wp:attachment":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media?parent=21119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/categories?post=21119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/tags?post=21119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}