{"id":21085,"date":"2026-05-08T21:00:21","date_gmt":"2026-05-08T20:00:21","guid":{"rendered":"https:\/\/informacionlocal.es\/exposiciones-juegos-tradicionales-y-talleres-de-oficio-artesanal-en-la-carpa-institucional-de-la-xxxvii-feria-insular-de-artesania\/"},"modified":"2026-05-08T21:00:21","modified_gmt":"2026-05-08T20:00:21","slug":"exposiciones-juegos-tradicionales-y-talleres-de-oficio-artesanal-en-la-carpa-institucional-de-la-xxxvii-feria-insular-de-artesania","status":"publish","type":"post","link":"https:\/\/informacionlocal.es\/it\/exposiciones-juegos-tradicionales-y-talleres-de-oficio-artesanal-en-la-carpa-institucional-de-la-xxxvii-feria-insular-de-artesania\/","title":{"rendered":"Exposiciones, juegos tradicionales y talleres de oficio artesanal en la carpa institucional de la XXXVII Feria insular de Artesan\u00eda"},"content":{"rendered":"<div class=\"elementor-widget-container\">\n<p><strong>Exposiciones, juegos tradicionales y talleres de oficio artesanal en la carpa institucional de la XXXVII Feria insular de Artesan\u00eda<\/strong><\/p>\n<p><strong>\u2022 La Organizaci\u00f3n, Ayuntamiento de Antigua y Fundaci\u00f3n Colectivo Mafasca, agradecen la presencia, esfuerzo y calidad de las exposiciones ofrecidas por todos los ayuntamientos y cabildos de Gran Canaria, Tenerife y Fuerteventura.<\/strong><\/p>\n<p>La Feria Insular de Artesan\u00eda acoge en la carpa institucional la representaci\u00f3n de todos los ayuntamientos de la isla, los cabildos de Gran Canaria, Tenerife y Fuerteventura, as\u00ed como la exposici\u00f3n de la Asociaci\u00f3n de Artesanos Creativos de Fuerteventura.<\/p>\n<p>El alcalde de Antigua, Mat\u00edas Pe\u00f1a Garc\u00eda, agradece la participaci\u00f3n de los ayuntamientos y cabildos en la Feria Insular de Artesan\u00eda, as\u00ed como felicita el resultado de los trabajos expuestos, artesan\u00edas y oficios referentes en cada municipio o isla.<\/p>\n<p>La Carpa Institucional de la Feria acoge talleres de oficios artesanales, gratuitos y abiertos a todas las edades, ofreciendo adem\u00e1s juegos infantiles tradicionales, y exposiciones permanentes de fotograf\u00eda o artesan\u00edas en reconocimiento de principales artesanos y artesanas, referentes del pasado y a\u00fan protagonistas hoy en la historia de la artesan\u00eda canaria en todas sus variedades.<\/p>\n<p>El Ayuntamiento de La Oliva, con el lema El arte de los tintes naturales, ofrece texturas y tintes que son explicados por un maestro artesano de este oficio tradicional. El Ayuntamiento de Betancuria dedica su exp\u00f3sitor a trabajos realizados con Junco, ca\u00f1a y p\u00edrgano. El Ayuntamiento de Puerto del Rosario expone con el lema Tejiendo Puerto, cada nudo cuenta, cada mano suma, disponiendo un artesano maestro de los nudos y cuerdas. El Ayuntamiento de Tuineje traslada la maquinaria para trabajar los asistentes aquellos Oficios con alma, fuego, metal y manos, mientras que el ayuntamiento de P\u00e1jara rescata la tener\u00eda de Mesque y la historia de los Oficios del ayer, como la curtider\u00eda. El Ayuntamiento de Antigua y la Fundaci\u00f3n Colectivo Mafasca dedican su espacio a los oficios tradicionales, ofreciendo un espacio de aprendizaje de la historia de la artesan\u00eda en la isla.<\/p>\n<p>Por su parte el Cabildo de Tenerife expone una variedad de trabajos que son identidad de la isla, desde cestos, atuendos tradicionales, juguetes de anta\u00f1o y calados. EL Cabildo de Gran Canaria, dedica su exposici\u00f3n a la historia reflejada en las im\u00e1genes del fot\u00f3grafo Francisco Rojas Fari\u00f1as, y el Cabildo de Fuerteventura, destaca la sombrerer\u00eda m\u00e1s tradicional e identificativa.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>Exposiciones, juegos tradicionales y talleres de oficio artesanal en la carpa institucional de la XXXVII Feria insular de Artesan\u00eda<\/strong><\/p>\n","protected":false},"author":1,"featured_media":21087,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[59],"tags":[82],"class_list":["post-21085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antigua","tag-fuerteventura"],"jetpack_featured_media_url":"https:\/\/informacionlocal.es\/wp-content\/uploads\/2026\/05\/1j5a1935-scaled-1.jpg","_links":{"self":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/21085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/comments?post=21085"}],"version-history":[{"count":0,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/21085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media\/21087"}],"wp:attachment":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media?parent=21085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/categories?post=21085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/tags?post=21085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}