{"id":21019,"date":"2026-05-08T14:01:32","date_gmt":"2026-05-08T13:01:32","guid":{"rendered":"https:\/\/informacionlocal.es\/el-plazo-para-reservar-mesas-en-el-gran-baile-de-taifas-abre-este-lunes-11-de-mayo-a-partir-de-las-17-00-horas\/"},"modified":"2026-05-08T14:01:32","modified_gmt":"2026-05-08T13:01:32","slug":"el-plazo-para-reservar-mesas-en-el-gran-baile-de-taifas-abre-este-lunes-11-de-mayo-a-partir-de-las-17-00-horas","status":"publish","type":"post","link":"https:\/\/informacionlocal.es\/it\/el-plazo-para-reservar-mesas-en-el-gran-baile-de-taifas-abre-este-lunes-11-de-mayo-a-partir-de-las-17-00-horas\/","title":{"rendered":"\ufeffEl plazo para reservar mesas en el Gran Baile de Taifas abre este lunes 11 de mayo a partir de las 17.00 horas"},"content":{"rendered":"<div class=\"entry-content\"><strong>8 mayo, 2026<\/strong><\/p>\n<p><\/p>\n<p><em>Actuar\u00e1n agrupaci\u00f3n<br \/>\nTababaire, las parrandas El Callao, El Golpito, Los Muchachos y el Alpiste, as\u00ed<br \/>\ncomo alumnado de las sedes de Valles de Ortega y La Oliva de la Escuela Insular<br \/>\nde M\u00fasica <\/em><\/p>\n<p><strong>Viernes, 7 de mayo de 2026.- <\/strong><\/p>\n<p>El Cabildo de Fuerteventura abrir\u00e1 el plazo<br \/>\npara reservar mesas en el Gran Baile de Taifas el pr\u00f3ximo lunes, 11 de mayo, a<br \/>\nlas 17.00 horas, a trav\u00e9s de la plataforma https:\/\/www.ecoentradas.com\/<\/p>\n<p>Ser\u00e1 posible reservar una mesa por sesi\u00f3n e<br \/>\nIP. Con el objetivo de gestionar la gran demanda existente, as\u00ed como garantizar<br \/>\nla ocupaci\u00f3n de las mesas, el solicitante deber\u00e1 abonar 10 euros en concepto de<br \/>\nfianza, que ser\u00e1 devuelta una vez confirmada su asistencia al evento el mismo<br \/>\nd\u00eda 29 de mayo en el baile. La fecha l\u00edmite para cancelar la reserva (con<br \/>\ndevoluci\u00f3n del dep\u00f3sito) es hasta el 25 de mayo. <\/p>\n<p>El Gran Baile de Taifas tendr\u00e1 lugar el 29 de<br \/>\nmayo en el Recinto Ferial de Puerto del Rosario, bajo la organizaci\u00f3n de la<br \/>\nConsejer\u00eda de Cultura del Cabildo de Fuerteventura, con la participaci\u00f3n del<br \/>\nresto de \u00e1reas de manera transversal, as\u00ed como la coorganizaci\u00f3n del Ayuntamiento<br \/>\nde Puerto del Rosario.<\/p>\n<p><strong>Agrupaciones<\/strong><\/p>\n<p>El Gran Baile de Taifas contar\u00e1 con grupos<br \/>\nmusicales tanto de Fuerteventura como del resto de islas. Como viene siendo<br \/>\nhabitual, abrir\u00e1 el alumnado de la Escuela Insular de M\u00fasica, correspondiendo<br \/>\nen esta edici\u00f3n a la sede de Valles de<\/p>\n<p>Ortega y La Oliva. Actuar\u00e1n, asimismo,<br \/>\nTababaire (Fuerteventura), Parranda El Callao (Fuerteventura), Parranda El<br \/>\nGolpito (Lanzarote), Parranda Los Muchachos (Tenerife) y Parranda El Alpiste<br \/>\n(Gran Canaria).<\/p>\n<p>Con m\u00e1s de veinte a\u00f1os de trayectoria, <strong>Tababaire<br \/>\n<\/strong>nace en La Oliva y cuenta con un amplio repertorio de m\u00fasica tradicional y<br \/>\npopular canaria, as\u00ed como otros g\u00e9neros de m\u00fasica de autor y popular latina.<\/p>\n<p>La parranda <strong>El Callao <\/strong>surgi\u00f3 en 2013<br \/>\npor la inquietud de tres parranderos con la intenci\u00f3n de transmitir la alegr\u00eda<br \/>\nde la m\u00fasica popular. Actualmente cuenta con cinco miembros, con un repertorio<br \/>\nque se compone de m\u00e1s de 25 canciones populares y otros temas de composici\u00f3n<br \/>\npropia.<\/p>\n<p>Formada por un grupo de j\u00f3venes amantes del<br \/>\nfolclore en 2004, la parranda <strong>El Golpito <\/strong>ha compartido escenario con<br \/>\ngrupos relevantes del \u00e1mbito de las islas, con una trayectoria que los ha<br \/>\nllevado por la mayor\u00eda de las fiestas populares de toda la geograf\u00eda canaria,<br \/>\nas\u00ed como a nivel nacional y Portugal.<\/p>\n<p>La parranda <strong>Los Muchachos <\/strong>surge en el<br \/>\na\u00f1o 2016, con miembros que proceden de distintas agrupaciones folcl\u00f3ricas y de<br \/>\nm\u00fasica popular. El repertorio que brindan incluye piezas que se bailaban en los<br \/>\nantiguos bailes de candil como pasodobles, isas o polkas. <\/p>\n<p>La parranda<strong> El Alpiste<\/strong> invita a bailar<br \/>\ncon un variado repertorio de m\u00fasica popular canaria y latinoamericana. La<br \/>\nenerg\u00eda y el ritmo contagioso de sus interpretaciones aseguran una experiencia<br \/>\nfestiva y llena de alegr\u00eda.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>8 mayo, 2026 Actuar\u00e1n agrupaci\u00f3n Tababaire, las parrandas El Callao, El Golpito, Los Muchachos y el Alpiste, as\u00ed como alumnado de las sedes de Valles de Ortega y La Oliva [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21021,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[58],"tags":[82],"class_list":["post-21019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cabildo","tag-fuerteventura"],"jetpack_featured_media_url":"https:\/\/informacionlocal.es\/wp-content\/uploads\/2026\/05\/bailedetaifas.jpg","_links":{"self":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/21019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/comments?post=21019"}],"version-history":[{"count":0,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/21019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media\/21021"}],"wp:attachment":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media?parent=21019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/categories?post=21019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/tags?post=21019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}