{"id":19224,"date":"2026-03-26T17:03:03","date_gmt":"2026-03-26T17:03:03","guid":{"rendered":"https:\/\/informacionlocal.es\/la-policia-local-de-antigua-coordina-el-dispositivo-de-seguridad-de-feaga-26\/"},"modified":"2026-03-26T17:03:03","modified_gmt":"2026-03-26T17:03:03","slug":"la-policia-local-de-antigua-coordina-el-dispositivo-de-seguridad-de-feaga-26","status":"publish","type":"post","link":"https:\/\/informacionlocal.es\/it\/la-policia-local-de-antigua-coordina-el-dispositivo-de-seguridad-de-feaga-26\/","title":{"rendered":"La Polic\u00eda Local de Antigua coordina el dispositivo de seguridad de FEAGA 26"},"content":{"rendered":"<div class=\"elementor-widget-container\">\n<p><strong>La Polic\u00eda Local de Antigua coordina el dispositivo de seguridad de FEAGA 26<\/strong><\/p>\n<p><strong>Antigua celebra la Junta de Seguridad de FEAGA 26<\/strong><\/p>\n<p><strong>\u2022 La Polic\u00eda Local de Antigua coordina el dispositivo de seguridad, accesibilidad y bienestar de los asistentes a FEAGA 2026.<\/strong><\/p>\n<p>Este jueves 26 de marzo en el Ayuntamiento de Antigua se ha celebrado la Junta de Seguridad FEAGA 2026 presidida por el alcalde, Mat\u00edas Pe\u00f1a Garc\u00eda y la directora insular de la Administraci\u00f3n General del Estado, Maria Jes\u00fas de la Cruz Montserrat.<\/p>\n<p>La Polic\u00eda Local de Antigua al mando de Inspector Jefe, Domingo Fr\u00e1nquiz, coordinar\u00e1 con la direcci\u00f3n del Plan de Seguridad, el dispositivo de seguridad, tr\u00e1nsito de veh\u00edculos, accesos al recinto y puntos de atenci\u00f3n de emergencias distribuidos en la Granja Experimental en Pozo Negro, que acoge la Feria de Agricultura, Ganader\u00eda y Pesca, FEAGA 2026 del 16 al 19 de abril.<\/p>\n<p>Como cada a\u00f1o este cometido lo afronta la Polic\u00eda Local de Antigua con la colaboraci\u00f3n de los cuerpos y fuerzas de seguridad del Estado, en este caso, la Guardia Civil, adem\u00e1s del trabajo desarrollado por Protecci\u00f3n Civil, el cuerpo de bomberos del cuerpo de Seguridad y emergencias del Cabildo de Fuerteventura, junto con Cruz Roja, dispositivos de emergencias y disposici\u00f3n de varias ambulancias de soporte avanzado, en el marco de un plan de seguridad reforzado tambi\u00e9n por vigilancia privada.<\/p>\n<p>La coordinaci\u00f3n de los diferentes agentes, cuerpos y dispositivos de seguridad permite garantizar el buen desarrollo de FEAGA 26, facilitando el disfrute, accesos c\u00f3modos e inclusivos, y tranquilidad del p\u00fablico asistente, especialmente familias, grupos o colectivos de todos los perfiles.<\/p>\n<p>Un plan de Seguridad confirmado por los responsables presentes, entre estos, el concejal de Seguridad y Emergencias del Ayuntamiento de Antigua, Fernando Estupi\u00f1\u00e1n, y t\u00e9cnicos del Cabildo de Fuerteventura.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>La Polic\u00eda Local de Antigua coordina el dispositivo de seguridad de FEAGA 26<\/strong><\/p>\n","protected":false},"author":1,"featured_media":19226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[59],"tags":[82,182],"class_list":["post-19224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antigua","tag-fuerteventura","tag-seguridad"],"jetpack_featured_media_url":"https:\/\/informacionlocal.es\/wp-content\/uploads\/2026\/03\/junta-de-seguridad-feaga-2026-1-scaled-1.jpg","_links":{"self":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/19224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/comments?post=19224"}],"version-history":[{"count":0,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/19224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media\/19226"}],"wp:attachment":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media?parent=19224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/categories?post=19224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/tags?post=19224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}