{"id":19144,"date":"2026-03-25T16:03:06","date_gmt":"2026-03-25T16:03:06","guid":{"rendered":"https:\/\/informacionlocal.es\/abierta-la-inscripcion-caminando-en-igualdad-en-ruta-a-la-atalayita\/"},"modified":"2026-03-25T16:03:06","modified_gmt":"2026-03-25T16:03:06","slug":"abierta-la-inscripcion-caminando-en-igualdad-en-ruta-a-la-atalayita","status":"publish","type":"post","link":"https:\/\/informacionlocal.es\/it\/abierta-la-inscripcion-caminando-en-igualdad-en-ruta-a-la-atalayita\/","title":{"rendered":"Abierta la inscripci\u00f3n Caminando en igualdad en Ruta a La Atalayita"},"content":{"rendered":"<div class=\"elementor-widget-container\">\n<p><strong>Abierta la inscripci\u00f3n Caminando en igualdad en Ruta a La Atalayita<\/strong><\/p>\n<p><strong>\u2022 La inscripci\u00f3n es gratuita y debe formalizarse por Registro de Entrada en el Ayuntamiento de Antigua, Tenencia de Alcald\u00eda en Caleta de Fuste o sede electr\u00f3nica. <\/strong><br \/><strong>\u2022 Plazas limitadas y abiertas a la inscripci\u00f3n de toda persona interesada, dando preferencia a empadronados en el municipio mayores de 60 a\u00f1os.<\/strong><\/p>\n<p>El Ayuntamiento de Antigua desde la concejal\u00eda de Servicios Sociales avisa de la apertura de inscripciones a la caminata en igualdad que tendr\u00e1 lugar el s\u00e1bado 11 de abril recorriendo la ruta de La Atalayita.<\/p>\n<p>Una ruta de senderismo en el entorno del poblado aborigen de La Atalayita hacia el pueblo costero de Pozo Negroi, con una dificultad baja, facilitando la participaci\u00f3n de toda persona interesada, afirma la concejala de Servicios Sociales, Am\u00e9rica Soto Betancor, con preferencia a las personas empadronadas en el Municipio con m\u00e1s de 60 a\u00f1os.<\/p>\n<p>Las plazas son limitadas y la inscripci\u00f3n a esta ruta guiada es gratuita, y se encuentra abierto el plazo para inscribirse, siempre por Registro de Entrada en el Ayuntamiento de Antigua, Tenencia de Alcald\u00eda en Caleta de Fuste o sede electr\u00f3nica en la web www.ayto-antigua.es<\/p>\n<p>El Ayuntamiento de Antigua desde la concejal\u00eda de Servicios Sociales ha organizado un programa de actividades saludables y formativas durante todo el mes de marzo y parte de abril, en el marco de celebraci\u00f3n del D\u00eda de la Mujer, defendiendo valores sobre igualdad y fomentando la participaci\u00f3n de vecinos y vecinas, especialmente dando preferencia a nuestros mayores se\u00f1ala el alcalde, Mat\u00edas Pe\u00f1a Garc\u00eda.<\/p>\n<p>\u00a0<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>Abierta la inscripci\u00f3n Caminando en igualdad en Ruta a La Atalayita<\/strong><\/p>\n","protected":false},"author":1,"featured_media":19146,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[59],"tags":[],"class_list":["post-19144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antigua"],"jetpack_featured_media_url":"https:\/\/informacionlocal.es\/wp-content\/uploads\/2026\/03\/whatsapp-image-2026-02-24-at-09-48-24-3.jpeg","_links":{"self":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/19144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/comments?post=19144"}],"version-history":[{"count":0,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/19144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media\/19146"}],"wp:attachment":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media?parent=19144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/categories?post=19144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/tags?post=19144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}