{"id":19138,"date":"2026-03-25T15:03:25","date_gmt":"2026-03-25T15:03:25","guid":{"rendered":"https:\/\/informacionlocal.es\/caleta-de-fuste-recibe-este-viernes-el-taller-creativo-de-pintura-textil\/"},"modified":"2026-03-25T15:03:25","modified_gmt":"2026-03-25T15:03:25","slug":"caleta-de-fuste-recibe-este-viernes-el-taller-creativo-de-pintura-textil","status":"publish","type":"post","link":"https:\/\/informacionlocal.es\/it\/caleta-de-fuste-recibe-este-viernes-el-taller-creativo-de-pintura-textil\/","title":{"rendered":"Caleta de Fuste recibe este viernes el Taller Creativo de Pintura Textil"},"content":{"rendered":"<div class=\"elementor-widget-container\">\n<p><strong>Caleta de Fuste recibe este viernes el Taller Creativo de Pintura Textil<\/strong><\/p>\n<p><strong>\u2022 El Taller Creativo de Pintura Textil tras impartirse en Triquivijate, valles de Ortega y Antigua, visita este viernes 27 de marzo, el centro cultural de Caleta de Fuste en horario de 17:30 a 20:30 horas. <\/strong><br \/><strong>\u2022 Las plazas son limitadas, dando preferencia a j\u00f3venes empadronados en el Municipio entre 12 y 30 a\u00f1os de edad. <\/strong><br \/><strong>\u2022 Inscripci\u00f3n gratuita por Registro de Entrada en el Ayuntamiento de Antigua, Tenencia de Alcald\u00eda en Caleta de Fuste o sede electr\u00f3nica en www.ayto-antigua.es<\/strong><\/p>\n<p>El Ayuntamiento de Antigua desde la concejal\u00eda de Juventud organiza el Taller Creativo de Pintura Textil, una propuesta de ocio y formaci\u00f3n que recorre todo el Municipio con \u00e9xito de participaci\u00f3n y una magn\u00edfica valoraci\u00f3n de las personas participantes.<\/p>\n<p>Una nueva iniciativa, se\u00f1ala el alcalde, Mat\u00edas Pe\u00f1a, que se suma a los talleres y eventos, siempre gratuitos, saludables y formativos que venimos organizando durante todo el a\u00f1o, en todos los pueblos y desde todas las \u00e1reas.<\/p>\n<p>Tras impartirse en Triquivijate, Valles de Ortega y Antigua, llega este viernes al centro cultural de Caleta de Fuste en horario de 17:30 a 20:30 horas, recuerda el concejal de Juventud, Pedro M. Armas Mart\u00edn, que recuerda que las plazas son limitadas, gratuitas, y debe formalizarse la inscripci\u00f3n por Registro de Entrada, dando preferencia en la participaci\u00f3n a j\u00f3venes empadronados en el municipio entre 12 y 30 a\u00f1os de edad.<\/p>\n<p>El \u00e9xito de este Taller Creativo de Pintura Textil es gracias a la artista dise\u00f1adora, Ver\u00f3nica Matoso Vera, que imparte los cursos, dando facilidades, trucos e ideas a todos y todas las asistentes, se\u00f1ala el concejal, permitiendo la libre creaci\u00f3n y expresi\u00f3n art\u00edstica de cada participante, que aprenden adem\u00e1s a dar colorido y una segunda vida a sus prendas.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>Caleta de Fuste recibe este viernes el Taller Creativo de Pintura Textil<\/strong><\/p>\n","protected":false},"author":1,"featured_media":19140,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[59],"tags":[69],"class_list":["post-19138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antigua","tag-eventos"],"jetpack_featured_media_url":"https:\/\/informacionlocal.es\/wp-content\/uploads\/2026\/03\/juventud-2.jpeg","_links":{"self":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/19138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/comments?post=19138"}],"version-history":[{"count":0,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/19138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media\/19140"}],"wp:attachment":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media?parent=19138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/categories?post=19138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/tags?post=19138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}