{"id":19132,"date":"2026-03-25T13:58:32","date_gmt":"2026-03-25T13:58:32","guid":{"rendered":"https:\/\/informacionlocal.es\/la-piscina-terapeutica-insular-se-encuentra-funcionando-a-pleno-rendimiento\/"},"modified":"2026-03-25T13:58:32","modified_gmt":"2026-03-25T13:58:32","slug":"la-piscina-terapeutica-insular-se-encuentra-funcionando-a-pleno-rendimiento","status":"publish","type":"post","link":"https:\/\/informacionlocal.es\/it\/la-piscina-terapeutica-insular-se-encuentra-funcionando-a-pleno-rendimiento\/","title":{"rendered":"La Piscina Terap\u00e9utica Insular se encuentra funcionando a pleno rendimiento"},"content":{"rendered":"<div class=\"entry-content\"><strong>25 marzo, 2026<\/strong><\/p>\n<p>La Piscina Terap\u00e9utica Insular se encuentra<br \/>\nfuncionando a pleno rendimiento. As\u00ed lo trasladaron la presidenta del Cabildo<br \/>\nde Fuerteventura, Lola Garc\u00eda, y el consejero de Acci\u00f3n Social, V\u00edctor Alonso,<br \/>\nen una visita realizada hasta este recurso para comprobar la gesti\u00f3n de este<br \/>\nservicio tan importante para personas usuarias y sus familiares, orientado a<br \/>\nmejorar su calidad de vida y bienestar.<\/p>\n<p>En esta primera fase de la puesta en marcha<br \/>\ndel recurso podr\u00e1n beneficiarse inicialmente los usuarios y usuarias de los<br \/>\ndiferentes Centros Sociosanitarios de Atenci\u00f3n a la Dependencia y Discapacidad<br \/>\ndel Cabildo de Fuerteventura. En una segunda fase, se trabajar\u00e1 en la<br \/>\nincorporaci\u00f3n paulatina del tejido social que interviene en el \u00e1rea de atenci\u00f3n<br \/>\na la discapacidad en la isla.<\/p>\n<p>La presidenta del Cabildo, Lola Garc\u00eda, ha<br \/>\npuesto en valor este servicio, \u201ctanto para las personas usuarias como sus<br \/>\nfamiliares y personas cuidadoras que merecen un respiro para su conciliaci\u00f3n<br \/>\nlaboral y familiar\u201d.<\/p>\n<p>Para el consejero V\u00edctor Alonso, \u201ces un<br \/>\norgullo ofrecer este servicio, en unas instalaciones ubicadas en el Centro<br \/>\nInsular de Atenci\u00f3n a la Discapacidad, \u00fanico complejo de estas caracter\u00edsticas<br \/>\nen Canarias\u201d. El mismo alberga adem\u00e1s de la Piscina Terap\u00e9utica, una zona<br \/>\ncom\u00fan, sal\u00f3n de actos, Centro Ocupacional, Residencia y Centro de D\u00eda de<br \/>\natenci\u00f3n a personas con Discapacidad y Residencia de Salud Mental (cuya<br \/>\nlicitaci\u00f3n ha sido recientemente adjudicada), convirti\u00e9ndose as\u00ed, asegura<br \/>\nAlonso, \u201cen un referente para la atenci\u00f3n de calidad a personas con<br \/>\ndiscapacidad\u201d. Durante la visita, estuvieron acompa\u00f1ados por Yurena Hern\u00e1ndez<br \/>\ncomo representante de la empresa adjudicataria del servicio, CLECE S.A.<\/p>\n<p>Tras haber culminado las labores de puesta a<br \/>\npunto y mejora de la accesibilidad necesarias ya se encuentran en<br \/>\nfuncionamiento las instalaciones ubicadas en el Complejo Insular de Atenci\u00f3n a<br \/>\nla Discapacidad en Puerto del Rosario.<\/p>\n<p>A principios de abril, se celebrar\u00e1 una<br \/>\njornada de puertas abiertas para familiares y las personas usuarias de los<br \/>\ncentros sociosanitarios de atenci\u00f3n a la dependencia y discapacidad, y se est\u00e1<br \/>\ntrabajando en otras actividades y acciones complementarias.<\/p>\n<p><strong>Equipamiento y personal<\/strong><\/p>\n<p>La Piscina Terap\u00e9utica Insular cuenta con un coordinador<br \/>\nencargado de la gesti\u00f3n y supervisi\u00f3n de las actividades, un t\u00e9cnico superior<br \/>\nen animaci\u00f3n de actividades f\u00edsicas y deportivas, dos monitoras de actividades,<br \/>\nauxiliar de servicios de limpieza y auxiliar de gesti\u00f3n administrativa.<\/p>\n<p>En cuanto a las instalaciones, el vaso<br \/>\nprincipal de esta nueva piscina est\u00e1 dotado con un elevador hidr\u00e1ulico para<br \/>\npersonas con movilidad reducida, tres escaleras de acceso de acero inoxidable e<br \/>\niluminaci\u00f3n. Adem\u00e1s, el vaso de hidroterapia cuenta con camas soplantes de<br \/>\naire, masajeadores de pies, jets rotatorios para masajes de gemelos,<br \/>\nisquiotibiales, dorsales, y lumbares; una cascada Bali, masajeador de<br \/>\ncervicales y rampa de acceso con pasamanos.<\/p>\n<p>El recurso cuenta, adem\u00e1s, con ducha bit\u00e9rmica<br \/>\nde hidroterapia multijet, ducha de hidroterapia con cambios t\u00e9rmicos del agua,<br \/>\nsauna y ba\u00f1o turco, dos duchas con pulsador y mezclador de temperatura, entre<br \/>\notros servicios.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>25 marzo, 2026 La Piscina Terap\u00e9utica Insular se encuentra funcionando a pleno rendimiento. As\u00ed lo trasladaron la presidenta del Cabildo de Fuerteventura, Lola Garc\u00eda, y el consejero de Acci\u00f3n Social, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[58],"tags":[82],"class_list":["post-19132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cabildo","tag-fuerteventura"],"jetpack_featured_media_url":"https:\/\/informacionlocal.es\/wp-content\/uploads\/2026\/03\/tt.jpeg","_links":{"self":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/19132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/comments?post=19132"}],"version-history":[{"count":0,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/19132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media\/19134"}],"wp:attachment":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media?parent=19132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/categories?post=19132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/tags?post=19132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}