{"id":17375,"date":"2026-02-07T18:00:45","date_gmt":"2026-02-07T18:00:45","guid":{"rendered":"https:\/\/informacionlocal.es\/antigua-premia-con-un-queso-a-los-campeones-absolutos-del-xxiv-cross-insular-y-7o-campo-a-traves\/"},"modified":"2026-02-07T18:00:45","modified_gmt":"2026-02-07T18:00:45","slug":"antigua-premia-con-un-queso-a-los-campeones-absolutos-del-xxiv-cross-insular-y-7o-campo-a-traves","status":"publish","type":"post","link":"https:\/\/informacionlocal.es\/it\/antigua-premia-con-un-queso-a-los-campeones-absolutos-del-xxiv-cross-insular-y-7o-campo-a-traves\/","title":{"rendered":"Antigua premia con un queso a los campeones absolutos del XXIV Cross Insular y 7\u00ba Campo a Trav\u00e9s"},"content":{"rendered":"<div class=\"elementor-widget-container\">\n<p><strong>Antigua premia con un queso a los campeones absolutos del XXIV Cross Insular y 7\u00ba Campo a Trav\u00e9s<\/strong><\/p>\n<p><strong>\u2022 En el brillante marco verde que ofrec\u00eda el circuito a los 320 atletas inscritos, se han disputado con nuevo r\u00e9cor de participaci\u00f3n en esta tradicional cita del atletismo organizada cada a\u00f1o por el Ayuntamiento de Antigua.<\/strong><\/p>\n<p><strong>\u2022 Eva Mar\u00eda Alonso Merino y Cesar Vera De Le\u00f3n campeones absolutos del Campeonato, recibiendo adem\u00e1s de Trofeo, un Queso de Antigua.<\/strong><\/p>\n<p><strong>\u2022 Como novedad, se ha disputado por primera vez en Antigua, la nueva prueba de Relevos que combina diferentes categor\u00edas en cada entrega del testigo.<\/strong><\/p>\n<p>Este s\u00e1bado 7 de febrero, el Ayuntamiento desde la concejal\u00eda de Deportes ha organizado la XXIV Cross Insular 2026 y el 7\u00ba Campeonato de Fuerteventura Campo a trav\u00e9s Municipio de Antigua.<\/p>\n<p>Una cita tradicional que logra batir r\u00e9cor de inscripciones cada a\u00f1o, alcanzando en esta edici\u00f3n los 320 atletas participantes, recibiendo todos y todas las categor\u00edas medallas al alcanzar meta, tras disputar una carrera en un impresionante entorno verde y en un d\u00eda inmejorable.<\/p>\n<p>El alcalde, Mat\u00edas Pe\u00f1a Garc\u00eda, ha felicitado a todos los participantes y ha hecho entrega del tradicional Queso de Antigua a los campeones absolutas de la competici\u00f3n, en esta ocasi\u00f3n, Eva Mar\u00eda Alonso Merino y Cesar Vera De Le\u00f3n.<\/p>\n<p>El concejal de Deportes, Samuel Torres Mesa, destacaba la din\u00e1mica organizaci\u00f3n y especialmente la imprescindible colaboraci\u00f3n de la Federaci\u00f3n Insular de Atletismo, cuyos representantes, junto con el consejero insular de \u00e1rea, Luis Gonz\u00e1lez, participaban en la entrega de trofeos a unos magn\u00edficos y magn\u00edficas atletas que sobre la pista dejan hasta el \u00faltimo aliento y fuera de circuito muestran generosidad y compa\u00f1erismo con sus rivales.<\/p>\n<p>\u00a0<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>Antigua premia con un queso a los campeones absolutos del XXIV Cross Insular y 7\u00ba Campo a Trav\u00e9s<\/strong><\/p>\n","protected":false},"author":1,"featured_media":17377,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[59],"tags":[82],"class_list":["post-17375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antigua","tag-fuerteventura"],"jetpack_featured_media_url":"https:\/\/informacionlocal.es\/wp-content\/uploads\/2026\/02\/000-medallas-para-todos-y-un-queso-para-los-ganadores-absolutos-2-scaled-1.jpg","_links":{"self":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/17375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/comments?post=17375"}],"version-history":[{"count":0,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/17375\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media\/17377"}],"wp:attachment":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media?parent=17375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/categories?post=17375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/tags?post=17375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}