{"id":17369,"date":"2026-02-07T11:00:44","date_gmt":"2026-02-07T11:00:44","guid":{"rendered":"https:\/\/informacionlocal.es\/nayeli-mendez-suarez-la-ninfa-del-mar-reina-infantil-del-carnaval-de-antigua-2026\/"},"modified":"2026-02-07T11:00:44","modified_gmt":"2026-02-07T11:00:44","slug":"nayeli-mendez-suarez-la-ninfa-del-mar-reina-infantil-del-carnaval-de-antigua-2026","status":"publish","type":"post","link":"https:\/\/informacionlocal.es\/it\/nayeli-mendez-suarez-la-ninfa-del-mar-reina-infantil-del-carnaval-de-antigua-2026\/","title":{"rendered":"Nayeli M\u00e9ndez Su\u00e1rez la Ninfa del mar Reina Infantil del Carnaval de Antigua 2026"},"content":{"rendered":"<div class=\"elementor-widget-container\">\n<p><strong>Nayeli M\u00e9ndez Su\u00e1rez la Ninfa del mar Reina Infantil del Carnaval de Antigua 2026<\/strong><\/p>\n<p><strong>\u2022 Nayeli M\u00e9ndez Su\u00e1rez, Reina Infantil del Carnaval de Antigua 2026 como Ninfa del Mar, acompa\u00f1ada de las Damas de Honor, por este orden, Sofia Lasso Reina, Sofia Santana Verde y Mar\u00eda L\u00f3pez Hern\u00e1ndez.<\/strong><\/p>\n<p>M\u00e1gica noche la vivida este viernes en la Gran Gala Reina Infantil Carnaval Antigua 2026, triunfando la Ninfa del mar, Nayeli M\u00e9ndez Su\u00e1rez, acompa\u00f1ada de las fant\u00e1sticas Damas de Honor, por este orden, Sofia Lasso Reina, Sofia Santana Verde y Mar\u00eda L\u00f3pez Hern\u00e1ndez.<\/p>\n<p>El selecto jurado estuvo presidido por el alcalde, Mat\u00edas Pe\u00f1a Garc\u00eda junto con la glamurosa reina saliente, Isabel Chesi, y conformado por el dise\u00f1ador Luis Miguel Rodr\u00edguez, la estilista, Patricia Susana Franc\u00e9s, el pregonero del Carnaval 2025, Rodrigo Carre\u00f1o y la modelo candidata por Fuerteventura a Miss Universo Canarias, Kiowa Andrea Bola\u00f1os.<\/p>\n<p>Una espectacular Gala de Reina Infantil Carnaval Antigua 2026 presentada por Baby Solano y amenizada por las coreograf\u00edas del elenco Academia Datana, adem\u00e1s del sorprendente Ra\u00fal El Mago con un p\u00fablico de familiares, vecinos y amistades que no dudo en volcarse en aplausos y v\u00edtores dedicados a cada candidata.<\/p>\n<p>Nayeli M\u00e9ndez Su\u00e1rez con la fantas\u00eda Ninfa del mar, reina del viaje por las culturas del mundo, dise\u00f1ada por Suso Monta\u00f1ez, confeccionada por Pepa Hern\u00e1ndez con la colaboraci\u00f3n de Carmen Marrero y Telly Garc\u00eda, y representando a la Asociaci\u00f3n Cultural El Campillo, result\u00f3 la gran triunfadora, coronada como Reina del Carnaval de Antigua 2026 por la cari\u00f1osa reina saliente, Isabel Chesi.<\/p>\n<p>Felicidades a la nueva Reina del Carnaval y felicidades a todos sus familiares y equipo magn\u00edfico que la ha acompa\u00f1ado, afirma el alcalde, Mat\u00edas Pe\u00f1a, que destaca tambi\u00e9n la magn\u00edfica puesta en escena y fantas\u00edas de las Damas de Honor.<\/p>\n<p>El concejal de Festejos, Pedro M. Armas Mart\u00edn, agradece al jurado, al p\u00fablico, a los profesionales de seguridad, t\u00e9cnicos de sonido y luces, y t\u00e9cnicas y operarios municipales, el magn\u00edfico espect\u00e1culo ofrecido en esta Gran Gala Infantil del Carnaval de Antigua 2026.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>Nayeli M\u00e9ndez Su\u00e1rez la Ninfa del mar Reina Infantil del Carnaval de Antigua 2026<\/strong><\/p>\n","protected":false},"author":1,"featured_media":17371,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[59],"tags":[82],"class_list":["post-17369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antigua","tag-fuerteventura"],"jetpack_featured_media_url":"https:\/\/informacionlocal.es\/wp-content\/uploads\/2026\/02\/00-gala-reina-infantil-carnaval-de-antigua-2026-6-scaled-1.jpg","_links":{"self":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/17369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/comments?post=17369"}],"version-history":[{"count":0,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/posts\/17369\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media\/17371"}],"wp:attachment":[{"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/media?parent=17369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/categories?post=17369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informacionlocal.es\/it\/wp-json\/wp\/v2\/tags?post=17369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}