{"id":21237,"date":"2026-05-12T23:01:47","date_gmt":"2026-05-12T22:01:47","guid":{"rendered":"https:\/\/informacionlocal.es\/la-concejalia-de-juventud-crea-el-programa-pajara-baila\/"},"modified":"2026-05-12T23:01:47","modified_gmt":"2026-05-12T22:01:47","slug":"la-concejalia-de-juventud-crea-el-programa-pajara-baila","status":"publish","type":"post","link":"https:\/\/informacionlocal.es\/de\/la-concejalia-de-juventud-crea-el-programa-pajara-baila\/","title":{"rendered":"La Concejal\u00eda de Juventud crea el programa \u2018P\u00e1jara Baila\u2019"},"content":{"rendered":"<div class=\"entry-content\">\n<p><b><i>Esta iniciativa se desarrolla en las localidades de La Lajita, Costa Calma, P\u00e1jara y Morro Jable y est\u00e1n dirigidas a j\u00f3venes mayores de 12 a\u00f1os<\/i><\/b><\/p>\n<p><span>El Ayuntamiento de P\u00e1jara, a trav\u00e9s de la Concejal\u00eda de Juventud, que dirige Juan Jos\u00e9 Viera, pone en marcha una nueva programaci\u00f3n de talleres de baile dirigidos a j\u00f3venes a partir de 12 a\u00f1os, con el objetivo de promover h\u00e1bitos de vida saludables, la convivencia y espacios de ocio alternativo en el municipio.<\/span><\/p>\n<p><span>Bajo el lema \u2018P\u00e1jara Baila\u2019, la propuesta acercar\u00e1 clases de salsa, bachata, merengue y rumba a diferentes localidades del municipio, concretamente La Lajita, Costa Calma, P\u00e1jara y Morro Jable. Los talleres est\u00e1n pensados para personas que deseen iniciarse en el baile en un ambiente din\u00e1mico, inclusivo y participativo.<\/span><\/p>\n<p><span>El concejal de Juventud, Juan Jos\u00e9 Viera, destaca la importancia de generar actividades adaptadas a los intereses de la poblaci\u00f3n juvenil, que \u201cgeneran v\u00ednculos sociales y espacios seguros donde los j\u00f3venes puedan expresarse y disfrutar\u201d.<\/span><\/p>\n<p><span>Por su parte, el alcalde de P\u00e1jara, Alejandro Jorge, subraya que \u201cdesde el Ayuntamiento seguimos apostando por iniciativas que fomenten la participaci\u00f3n juvenil y ofrezcan alternativas de ocio en las diferentes localidades del municipio\u201d.<\/span><\/p>\n<p><span>La programaci\u00f3n est\u00e1 dise\u00f1ada para que cualquier persona pueda participar, sin necesidad de experiencia previa ni pareja de baile, apostando adem\u00e1s por un entorno accesible e inclusivo. Desde la organizaci\u00f3n destacan que el proyecto busca convertir el baile en una herramienta de integraci\u00f3n, bienestar y desarrollo personal.<\/span><\/p>\n<p><span>Las plazas son limitadas y las personas interesadas podr\u00e1n formalizar su inscripci\u00f3n a trav\u00e9s del c\u00f3digo QR incluido en el cartel promocional difundido por la Concejal\u00eda de Juventud.<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><i>Esta iniciativa se desarrolla en las localidades de La Lajita, Costa Calma, P\u00e1jara y Morro Jable y est\u00e1n dirigidas a j\u00f3venes mayores de 12 a\u00f1os<\/i><\/p>\n","protected":false},"author":1,"featured_media":21239,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[63],"tags":[72],"class_list":["post-21237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pajara","tag-integracion"],"jetpack_featured_media_url":"https:\/\/informacionlocal.es\/wp-content\/uploads\/2026\/05\/whatsapp-image-2026-05-12-at-09-32-36.jpeg","_links":{"self":[{"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/posts\/21237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/comments?post=21237"}],"version-history":[{"count":0,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/posts\/21237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/media\/21239"}],"wp:attachment":[{"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/media?parent=21237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/categories?post=21237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/tags?post=21237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}