{"id":19260,"date":"2026-03-27T16:59:43","date_gmt":"2026-03-27T16:59:43","guid":{"rendered":"https:\/\/informacionlocal.es\/fuerteventura-impulsa-el-i-congreso-de-canarias-de-enfermeria-escolar\/"},"modified":"2026-03-27T16:59:43","modified_gmt":"2026-03-27T16:59:43","slug":"fuerteventura-impulsa-el-i-congreso-de-canarias-de-enfermeria-escolar","status":"publish","type":"post","link":"https:\/\/informacionlocal.es\/de\/fuerteventura-impulsa-el-i-congreso-de-canarias-de-enfermeria-escolar\/","title":{"rendered":"\ufeffFuerteventura impulsa el I Congreso de Canarias de Enfermer\u00eda Escolar"},"content":{"rendered":"<div class=\"entry-content\"><strong>27 marzo, 2026<\/strong><\/p>\n<p><em><strong>La Consejer\u00eda de Educaci\u00f3n del Cabildo y el \u00c1rea de Salud Firman un protocolo para organizar este encuentro profesional los d\u00edas 10 y 11 de abril<\/strong><\/em><\/p>\n<p>El Cabildo de Fuerteventura y la Gerencia de Servicios Sanitarios del \u00c1rea de Salud de Fuerteventura han firmado un protocolo general de colaboraci\u00f3n para la planificaci\u00f3n, organizaci\u00f3n y desarrollo del I Congreso de Canarias de Enfermer\u00eda Escolar, un encuentro que reunir\u00e1 a profesionales de los \u00e1mbitos sanitario y educativo para avanzar en la promoci\u00f3n de la salud en los centros educativos de las islas.<\/p>\n<p>El documento ha sido suscrito por el consejero insular de Educaci\u00f3n y Juventud del ejecutivo insular, Adargoma Hern\u00e1ndez, y el director del \u00c1rea de Salud de Fuerteventura, Tom\u00e1s Marcial P\u00e9rez, con el objetivo de establecer un marco de cooperaci\u00f3n interadministrativa que permita impulsar este evento formativo y de coordinaci\u00f3n profesional.<\/p>\n<p>El consejero de Educaci\u00f3n del Cabildo de Fuerteventura, Adargoma Hern\u00e1ndez, destac\u00f3 que \u201ceste congreso supone un paso importante para fortalecer la colaboraci\u00f3n entre educaci\u00f3n y sanidad y seguir avanzando en la promoci\u00f3n de h\u00e1bitos saludables y el bienestar del alumnado en nuestros centros educativos\u201d.<\/p>\n<p>Es una iniciativa que nace de enfermeras y dem\u00e1s personal sanitario de la Isla que trabaja de forma directa con los centros educativos. El Congreso se celebrar\u00e1 los d\u00edas 10 y 11 de abril de 2026 en el municipio de P\u00e1jara, y servir\u00e1 como espacio de encuentro para enfermeras y enfermeros escolares, docentes, profesionales sanitarios, estudiantes y representantes de la comunidad educativa. El programa combinar\u00e1 ponencias, mesas redondas y comunicaciones cient\u00edficas, adem\u00e1s de actividades vinculadas a la Feria de Salud Escolar del Sur.<\/p>\n<p>Esta iniciativa pretende reforzar la cooperaci\u00f3n entre los sistemas educativo y sanitario, impulsar la investigaci\u00f3n en salud escolar y visibilizar el papel de la enfermer\u00eda escolar como figura clave en la prevenci\u00f3n, la educaci\u00f3n para la salud y la atenci\u00f3n al alumnado en el entorno educativo.El protocolo firmado establece las bases de colaboraci\u00f3n institucional para la definici\u00f3n del programa cient\u00edfico, la coordinaci\u00f3n organizativa, la participaci\u00f3n de profesionales y la difusi\u00f3n del congreso, as\u00ed como para impulsar\u00a0futuras l\u00edneas de cooperaci\u00f3n en el \u00e1mbito de la salud escolar en Canarias.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>27 marzo, 2026 La Consejer\u00eda de Educaci\u00f3n del Cabildo y el \u00c1rea de Salud Firman un protocolo para organizar este encuentro profesional los d\u00edas 10 y 11 de abril El [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[58],"tags":[73,82,74],"class_list":["post-19260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cabildo","tag-educacion","tag-fuerteventura","tag-sanidad"],"jetpack_featured_media_url":"https:\/\/informacionlocal.es\/wp-content\/uploads\/2026\/03\/rrgr.jpeg","_links":{"self":[{"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/posts\/19260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/comments?post=19260"}],"version-history":[{"count":0,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/posts\/19260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/media\/19262"}],"wp:attachment":[{"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/media?parent=19260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/categories?post=19260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/tags?post=19260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}