{"id":17417,"date":"2026-02-10T16:00:59","date_gmt":"2026-02-10T16:00:59","guid":{"rendered":"https:\/\/informacionlocal.es\/antigua-abre-la-inscripcion-a-la-feria-insular-de-artesania-fuerteventura-2026\/"},"modified":"2026-02-10T16:00:59","modified_gmt":"2026-02-10T16:00:59","slug":"antigua-abre-la-inscripcion-a-la-feria-insular-de-artesania-fuerteventura-2026","status":"publish","type":"post","link":"https:\/\/informacionlocal.es\/de\/antigua-abre-la-inscripcion-a-la-feria-insular-de-artesania-fuerteventura-2026\/","title":{"rendered":"Antigua abre la inscripci\u00f3n a la Feria Insular de Artesan\u00eda Fuerteventura 2026"},"content":{"rendered":"<div class=\"elementor-widget-container\">\n<p>FERIA INSULAR DE ARTESAN\u00cdA ANTIGUA 2026-BASES DE PARTICIPACI\u00d3N E INSCRIPCI\u00d3N<\/p>\n<p><strong>\u2022 Publicadas las Bases de Participaci\u00f3n en la XXXVII Feria Insular de Artesan\u00eda que se celebra en la plaza y calles c\u00e9ntricas de Antigua del 7 al 10 de mayo. <\/strong><br \/><strong>\u2022 El plazo de inscripci\u00f3n finaliza el 4 de marzo. <\/strong><br \/><strong>\u2022 Las Bases pueden consultarse en el Tabl\u00f3n de Anuncios de la web www.ayto-antigua.es o el departamento de Cultura.<\/strong><\/p>\n<p>La Organizaci\u00f3n de la Feria Insular de Artesan\u00eda, Ayuntamiento de Antigua y Fundaci\u00f3n Colectivo Mafasca, anuncia la publicaci\u00f3n de las Bases de Participaci\u00f3n de artesanos y artesanas de Fuerteventura y todas las islas en la trig\u00e9simo s\u00e9ptima edici\u00f3n que se celebra del 7 al 10 de mayo en la plaza de Antigua y calles aleda\u00f1as.<\/p>\n<p>La inscripci\u00f3n es gratuita como cada a\u00f1o, facilitando desde la Organizaci\u00f3n, el puesto, la iluminaci\u00f3n, la seguridad de los trabajos y piezas expuestas, as\u00ed como el albergue y desplazamiento al mismo, para todos los artesanos y las artesanas, afirma el alcalde, Mat\u00edas Pe\u00f1a Garc\u00eda.<\/p>\n<p>El principal y permanente criterio para la participaci\u00f3n en la Feria Insular de Artesan\u00eda es presentar la acreditaci\u00f3n del carn\u00e9 de artesan\u00eda en cualquiera de sus modalidades y oficios, explica el concejal de Cultura, Jonathan Pe\u00f1a, con la finalidad de garantizar la esencia misma de respaldar al sector y al propio oficio artesanal.<\/p>\n<p>La presidenta de la Fundaci\u00f3n Colectivo Mafasca, Nereida Brito Morales, anima a la participaci\u00f3n en una de las citas de artesan\u00eda m\u00e1s importante del calendario anual de Ferias de Canarias, en la que siempre son bien acogidos los artesanos y artesanas, poniendo todos los medios en promocionar sus oficios, sus nombres, marcas y piezas, con el fin de impulsar las ventas y por lo tanto su econom\u00eda.<\/p>\n<p>El plazo de inscripci\u00f3n permanece abierto hasta el 4 de marzo, debiendo entregarse la solicitud en el Departamento de Cultura del Ayuntamiento de Antigua o por email a la direcci\u00f3n feriaartesaniaantigua@gmail.com<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>FERIA INSULAR DE ARTESAN\u00cdA ANTIGUA 2026-BASES DE PARTICIPACI\u00d3N E INSCRIPCI\u00d3N \u2022 Publicadas las Bases de Participaci\u00f3n en la XXXVII Feria Insular de Artesan\u00eda que se celebra en la plaza y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17419,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[59],"tags":[82],"class_list":["post-17417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antigua","tag-fuerteventura"],"jetpack_featured_media_url":"https:\/\/informacionlocal.es\/wp-content\/uploads\/2026\/02\/abierta-la-inscripcion-a-la-feria-insular-de-artesania-fuerteventura-2026.jpg","_links":{"self":[{"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/posts\/17417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/comments?post=17417"}],"version-history":[{"count":0,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/posts\/17417\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/media\/17419"}],"wp:attachment":[{"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/media?parent=17417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/categories?post=17417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/tags?post=17417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}