{"id":17399,"date":"2026-02-09T18:00:56","date_gmt":"2026-02-09T18:00:56","guid":{"rendered":"https:\/\/informacionlocal.es\/el-cabildo-de-fuerteventura-remite-al-ayuntamiento-de-tuineje-el-plan-municipal-de-emergencias\/"},"modified":"2026-02-09T18:00:56","modified_gmt":"2026-02-09T18:00:56","slug":"el-cabildo-de-fuerteventura-remite-al-ayuntamiento-de-tuineje-el-plan-municipal-de-emergencias","status":"publish","type":"post","link":"https:\/\/informacionlocal.es\/de\/el-cabildo-de-fuerteventura-remite-al-ayuntamiento-de-tuineje-el-plan-municipal-de-emergencias\/","title":{"rendered":"El Cabildo de Fuerteventura remite al Ayuntamiento de Tuineje el Plan Municipal de Emergencias"},"content":{"rendered":"<div class=\"entry-content\"><strong>9 febrero, 2026<\/strong><\/p>\n<p><em><strong>El PEMU de Tuineje, que deber\u00e1 ser aprobado en el Pleno municipal, ser\u00e1 el tercero de Fuerteventura<\/strong><\/em><\/p>\n<p><em><strong>Lolina Negr\u00edn: \u201cLa remisi\u00f3n de este documento es una gran noticia para el conjunto de la isla y un buen ejemplo del fruto del trabajo coordinado entre administraciones\u201d<\/strong><\/em><\/p>\n<p><em><strong>David Herrera: \u201cEs un paso importante para Tuineje porque nos refuerza para actuar en caso de una emergencia y si fuera necesario apoyar con nuestros efectivos a otros municipios\u201d<\/strong><\/em><\/p>\n<p>El Cabildo de Fuerteventura, a trav\u00e9s de la Consejer\u00eda de Emergencias, ha remitido al Ayuntamiento de Tuineje el documento del Plan de Emergencia Municipal (PEMU) de ese municipio para su aprobaci\u00f3n en el Pleno. Ser\u00e1 el tercer PEMU activo de Fuerteventura y surge de la iniciativa del Cabildo de ayudar en esta materia a los municipios de menos de 20.000 habitantes. Tuineje ha sido el primer documento en ser remitido a su ayuntamiento, estando los de Betancuria y Antigua en su recta final de redacci\u00f3n.<\/p>\n<p>Lolina Negr\u00edn, consejera de Seguridad y Emergencias del Cabildo, afirma que \u201cla remisi\u00f3n de este documento es una gran noticia para el conjunto de la isla y un buen ejemplo del fruto del trabajo coordinado entre administraciones\u201d. Recuerda que los PEMU son \u201cclave para la capacidad operativa en toda la isla y que los servicios de emergencias trabajen de forma coordinada y en apoyo mutuo\u201d.<\/p>\n<p>David Herrera, concejal de Seguridad, Emergencias y Protecci\u00f3n Civil del Ayuntamiento, valora muy positivamente el documento y la trascendencia de esta iniciativa de apoyo entre administraciones. \u201cEs un paso importante para Tuineje porque nos refuerza para actuar en caso de una emergencia y si fuera necesario apoyar con nuestros efectivos a otros municipios\u201d, apunta David Herrera. \u201cEs una garant\u00eda para la poblaci\u00f3n y un plus de seguridad para los sectores econ\u00f3micos\u201d, a\u00f1ade.<\/p>\n<p>El PEMU de Tuineje, que se encuentra ya en poder del Ayuntamiento, deber\u00e1 ahora ser aprobado por el Pleno municipal para su entrada en vigor. En este sentido, el Cabildo tom\u00f3 la iniciativa de ayudar a los municipios de menos de 20.000 habitantes a redactar sus PEMU, y elevar as\u00ed su efectividad y capacidad de reacci\u00f3n en caso de emergencia, ya que las distintas densidades de poblaci\u00f3n entre municipios conllevan distintos niveles de dotaciones humanas y materiales especializadas en cada territorio que necesitan compensarse y coordinarse para mejorar su efectividad.<\/p>\n<p>Por ello, el pasado a\u00f1o la Consejer\u00eda de Seguridad y Emergencias del Cabildo inici\u00f3 tres mesas de trabajo para coordinar la redacci\u00f3n de los PEMU con los ayuntamientos de Tuineje, Antigua y Betancuria. El objetivo de esa iniciativa era ayudar a los municipios de menos de 20.000 habitantes a redactar sus PEMU y elevar as\u00ed sus niveles de reacci\u00f3n en situaciones de crisis, equilibrando en todo el territorio insular la efectividad para el control de una emergencia. El documento de Tuineje ya se ha entregado y los de Antigua y Betancuria est\u00e1n en su recta final.<\/p>\n<p>Los Planes de Emergencia Municipal permiten identificar riesgos, coordinar recursos y establecer mecanismos de movilizaci\u00f3n y coordinaci\u00f3n entre las distintas administraciones para garantizar una respuesta efectiva ante emergencias. Con los PEMU se garantiza la coordinaci\u00f3n de recursos p\u00fablicos en situaciones de emergencia y mejorar la respuesta ante incidentes, sin importar si el suceso se ha producido en un municipio o en otro.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>9 febrero, 2026 El PEMU de Tuineje, que deber\u00e1 ser aprobado en el Pleno municipal, ser\u00e1 el tercero de Fuerteventura Lolina Negr\u00edn: \u201cLa remisi\u00f3n de este documento es una gran [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[58],"tags":[82,65],"class_list":["post-17399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cabildo","tag-fuerteventura","tag-municipios"],"jetpack_featured_media_url":"https:\/\/informacionlocal.es\/wp-content\/uploads\/2026\/02\/dddg.jpeg","_links":{"self":[{"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/posts\/17399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/comments?post=17399"}],"version-history":[{"count":0,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/posts\/17399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/media\/17401"}],"wp:attachment":[{"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/media?parent=17399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/categories?post=17399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informacionlocal.es\/de\/wp-json\/wp\/v2\/tags?post=17399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}